{"id":35426,"date":"2026-05-13T04:10:49","date_gmt":"2026-05-13T02:10:49","guid":{"rendered":"https:\/\/hmtm.de\/personen\/mizuko-uchida\/"},"modified":"2026-05-13T04:11:13","modified_gmt":"2026-05-13T02:11:13","slug":"mizuko-uchida","status":"publish","type":"person","link":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/","title":{"rendered":"Mizuko Uchida"},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","institutes":[1409],"letters":[1213],"class_list":["post-35426","person","type-person","status-publish","hentry","institute-institute-3-vocal-theatre-performance","letter-u-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mizuko Uchida - HMTM<\/title>\n<meta name=\"description\" content=\"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mizuko Uchida - HMTM\" \/>\n<meta property=\"og:description\" content=\"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/\" \/>\n<meta property=\"og:site_name\" content=\"HMTM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hochschule-fr-Musik-und-Theater-Mnchen-310270902396373\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T02:11:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hmtm.de\\\/en\\\/people\\\/mizuko-uchida\\\/\",\"url\":\"https:\\\/\\\/hmtm.de\\\/en\\\/people\\\/mizuko-uchida\\\/\",\"name\":\"Mizuko Uchida - HMTM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hmtm.de\\\/#website\"},\"datePublished\":\"2026-05-13T02:10:49+00:00\",\"dateModified\":\"2026-05-13T02:11:13+00:00\",\"description\":\"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hmtm.de\\\/en\\\/people\\\/mizuko-uchida\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hmtm.de\\\/en\\\/people\\\/mizuko-uchida\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hmtm.de\\\/en\\\/people\\\/mizuko-uchida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hmtm.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personen\",\"item\":\"https:\\\/\\\/hmtm.de\\\/personen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mizuko Uchida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hmtm.de\\\/#website\",\"url\":\"https:\\\/\\\/hmtm.de\\\/\",\"name\":\"HMTM\",\"description\":\"Hochschule f\u00fcr Musik und Theater M\u00fcnchen\",\"publisher\":{\"@id\":\"https:\\\/\\\/hmtm.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hmtm.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hmtm.de\\\/#organization\",\"name\":\"Hochschule f\u00fcr Musik und Theater M\u00fcnchen\",\"url\":\"https:\\\/\\\/hmtm.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/hmtm.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hmtm.de\\\/wp-content\\\/uploads\\\/logos\\\/hmtm_logo.svg\",\"contentUrl\":\"https:\\\/\\\/hmtm.de\\\/wp-content\\\/uploads\\\/logos\\\/hmtm_logo.svg\",\"width\":169,\"height\":85,\"caption\":\"Hochschule f\u00fcr Musik und Theater M\u00fcnchen\"},\"image\":{\"@id\":\"https:\\\/\\\/hmtm.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Hochschule-fr-Musik-und-Theater-Mnchen-310270902396373\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCruQL0dtip2Y6-x9XM8S_cA\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/school\\\/hochschule-f-r-musik-und-theater-m-nchen\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/hochschulefuermusikundtheatermuenchen\",\"https:\\\/\\\/www.instagram.com\\\/hmtm_offiziell\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mizuko Uchida - HMTM","description":"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/","og_locale":"en_GB","og_type":"article","og_title":"Mizuko Uchida - HMTM","og_description":"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.","og_url":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/","og_site_name":"HMTM","article_publisher":"https:\/\/www.facebook.com\/Hochschule-fr-Musik-und-Theater-Mnchen-310270902396373\/","article_modified_time":"2026-05-13T02:11:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/","url":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/","name":"Mizuko Uchida - HMTM","isPartOf":{"@id":"https:\/\/hmtm.de\/#website"},"datePublished":"2026-05-13T02:10:49+00:00","dateModified":"2026-05-13T02:11:13+00:00","description":"Finden Sie hier die richtigen Ansprechpartner*innen der HMTM. Gerne helfen wir Ihnen bei ihrem Anliegen weiter.","breadcrumb":{"@id":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hmtm.de\/en\/people\/mizuko-uchida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hmtm.de\/en\/"},{"@type":"ListItem","position":2,"name":"Personen","item":"https:\/\/hmtm.de\/personen\/"},{"@type":"ListItem","position":3,"name":"Mizuko Uchida"}]},{"@type":"WebSite","@id":"https:\/\/hmtm.de\/#website","url":"https:\/\/hmtm.de\/","name":"HMTM","description":"Hochschule f\u00fcr Musik und Theater M\u00fcnchen","publisher":{"@id":"https:\/\/hmtm.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hmtm.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/hmtm.de\/#organization","name":"Hochschule f\u00fcr Musik und Theater M\u00fcnchen","url":"https:\/\/hmtm.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/hmtm.de\/#\/schema\/logo\/image\/","url":"https:\/\/hmtm.de\/wp-content\/uploads\/logos\/hmtm_logo.svg","contentUrl":"https:\/\/hmtm.de\/wp-content\/uploads\/logos\/hmtm_logo.svg","width":169,"height":85,"caption":"Hochschule f\u00fcr Musik und Theater M\u00fcnchen"},"image":{"@id":"https:\/\/hmtm.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hochschule-fr-Musik-und-Theater-Mnchen-310270902396373\/","https:\/\/www.youtube.com\/channel\/UCruQL0dtip2Y6-x9XM8S_cA\/","https:\/\/de.linkedin.com\/school\/hochschule-f-r-musik-und-theater-m-nchen\/","https:\/\/www.xing.com\/pages\/hochschulefuermusikundtheatermuenchen","https:\/\/www.instagram.com\/hmtm_offiziell\/"]}]}},"_links":{"self":[{"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/people\/35426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/types\/person"}],"wp:attachment":[{"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/media?parent=35426"}],"wp:term":[{"taxonomy":"institute","embeddable":true,"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/institutes?post=35426"},{"taxonomy":"letter","embeddable":true,"href":"https:\/\/hmtm.de\/en\/wp-json\/wp\/v2\/letters?post=35426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}